{"id":3614,"date":"2017-04-03T07:11:10","date_gmt":"2017-04-03T07:11:10","guid":{"rendered":"http:\/\/artetremila.it\/wordpress\/?p=3614"},"modified":"2017-04-03T07:11:10","modified_gmt":"2017-04-03T07:11:10","slug":"pomezia-un-giardino-in-comune-scelti-i-tre-progetti-migliori","status":"publish","type":"post","link":"https:\/\/artetremila.it\/wordpress\/pomezia-un-giardino-in-comune-scelti-i-tre-progetti-migliori\/","title":{"rendered":"Pomezia: Un giardino in comune-Scelti i tre progetti migliori."},"content":{"rendered":"<p>Concorso di idee UN GIARDINO IN COMUNE. Scelti i tre progetti migliori.<\/p>\n<p>Premiazione marted\u00ec 4 aprile alle ore 11.30 presso la Biblioteca comunale, Sala conferenze<!--more--><\/p>\n<p><strong><b>\u00a0<a href=\"http:\/\/artetremila.it\/wordpress\/wp-content\/uploads\/2017\/04\/premiazioneGiardini.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3616\" src=\"http:\/\/artetremila.it\/wordpress\/wp-content\/uploads\/2017\/04\/premiazioneGiardini-212x300.jpg\" alt=\"\" width=\"175\" height=\"248\" data-id=\"3616\" srcset=\"https:\/\/artetremila.it\/wordpress\/wp-content\/uploads\/2017\/04\/premiazioneGiardini-212x300.jpg 212w, https:\/\/artetremila.it\/wordpress\/wp-content\/uploads\/2017\/04\/premiazioneGiardini.jpg 699w\" sizes=\"(max-width: 175px) 100vw, 175px\" \/><\/a><\/b><\/strong><\/p>\n<p>Grande successo per il concorso di idee UN GIARDINO IN COMUNE volto alla riqualificazione dei Giardini Petrucci di piazza Indipendenza; Trentasei i progetti presentati dagli studenti e laureati della facolt\u00e0 di Architettura e del corso di laurea in Ingegneria edile della Sapienza Universit\u00e0 di Roma.<\/p>\n<p>La Commissione di gara ha individuato i tre progetti vincitori delle tre borse di studio (5.000 euro; 2.500 euro e 1.000 euro) messe a disposizione dal Comune di Pomezia e che verranno consegnate ai ragazzi durante la cerimonia di premiazione che si svolger\u00e0 marted\u00ec 4 aprile alle 11.30 presso la Biblioteca comunale di largo Catone.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cSiamo davvero soddisfatti della grande partecipazione registrata e della qualit\u00e0 dei progetti presentati \u2013 spiega il Sindaco Fabio Fucci \u2013 Il progetto che si \u00e8 aggiudicato il primo premio sar\u00e0 concretamente attuato. Una porzione del parco comunale Giardini Petrucci verr\u00e0 quindi ristrutturato e reso maggiormente fruibile alla cittadinanza, sulla base dell\u2019idea e del contributo che questi ragazzi ci hanno fornito. Siamo lieti di premiare con le borse di studio messe a disposizione dal Comune chi ha lavorato alla progettazione di uno spazio pubblico molto caro alla cittadinanza di Pomezia. Crediamo nel talento dei giovani e abbiamo voluto premiare il merito e le loro capacit\u00e0: proprio per questo, oltre alla gratificazione delle borse di studio, nel bilancio del comune abbiamo inserito circa 180 mila euro da investire nell\u2019attuazione del progetto\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Alla premiazione, durante la quale verranno presentati i tre progetti vincitori, parteciperanno il Sindaco di Pomezia Fabio Fucci, l\u2019Assessore Lorenzo Sbizzera, il vice Preside della Facolt\u00e0 di Architettura dell\u2019Universit\u00e0 Sapienza di Roma Prof. Luca Ribichini e il Presidente della Commissione di Gara del concorso prof. Franco Zagari.<\/p>\n<p>&nbsp;<\/p>\n<p>Tutti i progetti partecipanti saranno esposti in mostra presso la Biblioteca comunale da marted\u00ec 4 aprile a sabato 8 aprile.<\/p>\n<p><em><i>\u00a0<\/i><\/em><\/p>\n<p>La graduatoria \u00e8 consultabile sul sito: <a href=\"http:\/\/www.comune.pomezia.rm.it\/un_giardino_in_comune\">http:\/\/www.comune.pomezia.rm.it\/un_giardino_in_comune<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concorso di idee UN GIARDINO IN COMUNE. Scelti i tre progetti migliori. Premiazione marted\u00ec 4 aprile alle ore 11.30 presso la Biblioteca comunale, Sala conferenze<\/p>\n","protected":false},"author":3,"featured_media":3503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[77],"tags":[],"_links":{"self":[{"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/posts\/3614"}],"collection":[{"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/comments?post=3614"}],"version-history":[{"count":2,"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/posts\/3614\/revisions"}],"predecessor-version":[{"id":3617,"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/posts\/3614\/revisions\/3617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/media\/3503"}],"wp:attachment":[{"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/media?parent=3614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/categories?post=3614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artetremila.it\/wordpress\/wp-json\/wp\/v2\/tags?post=3614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}